{"id":5755,"date":"2025-06-25T17:29:43","date_gmt":"2025-06-25T15:29:43","guid":{"rendered":"https:\/\/www.almar.it\/?page_id=5755"},"modified":"2026-06-08T14:10:35","modified_gmt":"2026-06-08T12:10:35","slug":"erklarung-zur-barrierefreiheit","status":"publish","type":"page","link":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/","title":{"rendered":"Erkl\u00e4rung zur Barrierefreiheit"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Website: https:\/\/www.almar.it<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Datum der Ver\u00f6ffentlichung der Erkl\u00e4rung: 25. Juni 2025<br>Letzte Aktualisierung: 25. Juni 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Almar verpflichtet sich, seine Website https:\/\/www.almar.it\/ gem\u00e4\u00df dem Gesetzesdekret Nr. 82\/2022 barrierefrei zug\u00e4nglich zu machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Konformit\u00e4t mit den Standards<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Website wurde unter Einhaltung der Web Content Accessibility Guidelines (WCAG) 2.1, Stufe AA, wie vom W3C-Konsortium definiert, entwickelt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aktueller Konformit\u00e4tsstatus<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Website https:\/\/www.almar.it\/ ist teilweise konform mit den Anforderungen gem\u00e4\u00df Anhang A der Norm UNI EN 301549:2018 (WCAG 2.1), aufgrund der nachfolgend aufgef\u00fchrten Nichtkonformit\u00e4ten:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle Icons (Warenkorb, Konto usw.) und die Bilder der News haben denselben Alt-Text, obwohl sie auf unterschiedliche Links verweisen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Texte und Schaltfl\u00e4chen weisen im Verh\u00e4ltnis zum Hintergrund einen unzureichenden Kontrast auf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Schaltfl\u00e4che zum Starten der Suche verf\u00fcgt \u00fcber kein Label oder keinen zug\u00e4nglichen Namen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Eingabefelder (Suche und Newsletter-Anmeldung) haben keine zug\u00e4ngliche Bezeichnung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Tastaturfokus ist f\u00fcr fast alle Elemente auf der Startseite nicht sichtbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Carousel ist nicht korrekt verwaltet: Die Folien k\u00f6nnen nicht per Tastatur gewechselt werden, die Inhalte sind verborgen und die Links nicht zug\u00e4nglich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Men\u00fc der Produktkategorien kann nicht per Tastatur ge\u00f6ffnet und navigiert werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Erstellung der Erkl\u00e4rung zur Barrierefreiheit<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Erkl\u00e4rung wurde am 10.10.2025 auf Grundlage einer von Dritten durchgef\u00fchrten Bewertung erstellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Analyse kombiniert manuelle Tests und Pr\u00fcfungen mit halbautomatischen Tools, die zu den vom W3C empfohlenen geh\u00f6ren und Techniken ber\u00fccksichtigen, die den WCAG 2.1 Richtlinien der Stufen A und AA entsprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Feedback und Kontaktinformationen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen Zug\u00e4nglichkeitsprobleme melden, Informationen in einem alternativen Format anfordern oder Navigationsschwierigkeiten mitteilen, indem Sie an folgende Adresse schreiben: sales@almar.it<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Verfahren zur Meldung an die AgID<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Falle einer unzureichenden Antwort oder ausbleibenden Antwort innerhalb von drei\u00dfig Tagen auf die Meldung oder Anfrage kann die betroffene Person eine Beschwerde \u00fcber folgenden Link einreichen: https:\/\/www.agid.gov.it\/it<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informationen zur Website<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f6ffentlichungsdatum der Website https:\/\/www.almar.it\/: letzte Version April 2023<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Verwendetes CMS f\u00fcr die Website: WordPress<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fortlaufendes Engagement<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Almar Drink &amp; Food Srl verpflichtet sich, eine barrierefreie und inklusive Navigation im Hinblick auf das Inkrafttreten des European Accessibility Act am 28. Juni 2025 zu gew\u00e4hrleisten, der die Anforderungen auch auf E-Commerce-Websites privater Unternehmen ausweiten wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Website: https:\/\/www.almar.it Datum der Ver\u00f6ffentlichung der Erkl\u00e4rung: 25. Juni 2025Letzte Aktualisierung: 25. Juni 2025 Almar verpflichtet sich, seine Website https:\/\/www.almar.it\/ gem\u00e4\u00df dem Gesetzesdekret Nr. 82\/2022 barrierefrei zug\u00e4nglich zu machen. Konformit\u00e4t mit den Standards Diese Website wurde unter Einhaltung der Web Content Accessibility Guidelines (WCAG) 2.1, Stufe AA, wie vom W3C-Konsortium definiert, entwickelt. Aktueller Konformit\u00e4tsstatus Die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-5755","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erkl\u00e4rung zur Barrierefreiheit - Almar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erkl\u00e4rung zur Barrierefreiheit - Almar\" \/>\n<meta property=\"og:description\" content=\"Website: https:\/\/www.almar.it Datum der Ver\u00f6ffentlichung der Erkl\u00e4rung: 25. Juni 2025Letzte Aktualisierung: 25. Juni 2025 Almar verpflichtet sich, seine Website https:\/\/www.almar.it\/ gem\u00e4\u00df dem Gesetzesdekret Nr. 82\/2022 barrierefrei zug\u00e4nglich zu machen. Konformit\u00e4t mit den Standards Diese Website wurde unter Einhaltung der Web Content Accessibility Guidelines (WCAG) 2.1, Stufe AA, wie vom W3C-Konsortium definiert, entwickelt. Aktueller Konformit\u00e4tsstatus Die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/\" \/>\n<meta property=\"og:site_name\" content=\"Almar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/almarmilano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T12:10:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/01\/logo-almar-500x500-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/de\\\/erklarung-zur-barrierefreiheit\\\/\",\"url\":\"https:\\\/\\\/www.almar.it\\\/de\\\/erklarung-zur-barrierefreiheit\\\/\",\"name\":\"Erkl\u00e4rung zur Barrierefreiheit - Almar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/#website\"},\"datePublished\":\"2025-06-25T15:29:43+00:00\",\"dateModified\":\"2026-06-08T12:10:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/de\\\/erklarung-zur-barrierefreiheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.almar.it\\\/de\\\/erklarung-zur-barrierefreiheit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/de\\\/erklarung-zur-barrierefreiheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.almar.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erkl\u00e4rung zur Barrierefreiheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/#website\",\"url\":\"https:\\\/\\\/www.almar.it\\\/\",\"name\":\"Almar Drink & Food\",\"description\":\"Preparati professionali Almar per bar, ristoranti e caff\u00e8\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/#organization\"},\"alternateName\":\"Almar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.almar.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/#organization\",\"name\":\"Almar Drink & Food srl\",\"url\":\"https:\\\/\\\/www.almar.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.almar.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-almar-500x500-1.png\",\"contentUrl\":\"https:\\\/\\\/www.almar.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-almar-500x500-1.png\",\"width\":500,\"height\":500,\"caption\":\"Almar Drink & Food srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/almarmilano\",\"https:\\\/\\\/www.instagram.com\\\/almar.gustoitaliano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/AlmarIT-Gusto-Italiano\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erkl\u00e4rung zur Barrierefreiheit - Almar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/","og_locale":"de_DE","og_type":"article","og_title":"Erkl\u00e4rung zur Barrierefreiheit - Almar","og_description":"Website: https:\/\/www.almar.it Datum der Ver\u00f6ffentlichung der Erkl\u00e4rung: 25. Juni 2025Letzte Aktualisierung: 25. Juni 2025 Almar verpflichtet sich, seine Website https:\/\/www.almar.it\/ gem\u00e4\u00df dem Gesetzesdekret Nr. 82\/2022 barrierefrei zug\u00e4nglich zu machen. Konformit\u00e4t mit den Standards Diese Website wurde unter Einhaltung der Web Content Accessibility Guidelines (WCAG) 2.1, Stufe AA, wie vom W3C-Konsortium definiert, entwickelt. Aktueller Konformit\u00e4tsstatus Die [&hellip;]","og_url":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/","og_site_name":"Almar","article_publisher":"https:\/\/www.facebook.com\/almarmilano","article_modified_time":"2026-06-08T12:10:35+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/01\/logo-almar-500x500-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/","url":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/","name":"Erkl\u00e4rung zur Barrierefreiheit - Almar","isPartOf":{"@id":"https:\/\/www.almar.it\/#website"},"datePublished":"2025-06-25T15:29:43+00:00","dateModified":"2026-06-08T12:10:35+00:00","breadcrumb":{"@id":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.almar.it\/de\/erklarung-zur-barrierefreiheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.almar.it\/de\/"},{"@type":"ListItem","position":2,"name":"Erkl\u00e4rung zur Barrierefreiheit"}]},{"@type":"WebSite","@id":"https:\/\/www.almar.it\/#website","url":"https:\/\/www.almar.it\/","name":"Almar Drink & Food","description":"Preparati professionali Almar per bar, ristoranti e caff\u00e8","publisher":{"@id":"https:\/\/www.almar.it\/#organization"},"alternateName":"Almar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.almar.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.almar.it\/#organization","name":"Almar Drink & Food srl","url":"https:\/\/www.almar.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.almar.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/03\/logo-almar-500x500-1.png","contentUrl":"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/03\/logo-almar-500x500-1.png","width":500,"height":500,"caption":"Almar Drink & Food srl"},"image":{"@id":"https:\/\/www.almar.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/almarmilano","https:\/\/www.instagram.com\/almar.gustoitaliano\/","https:\/\/www.youtube.com\/c\/AlmarIT-Gusto-Italiano"]}]}},"_links":{"self":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages\/5755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/comments?post=5755"}],"version-history":[{"count":1,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages\/5755\/revisions"}],"predecessor-version":[{"id":5756,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages\/5755\/revisions\/5756"}],"wp:attachment":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/media?parent=5755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}