{"id":5751,"date":"2024-02-01T10:06:22","date_gmt":"2024-02-01T09:06:22","guid":{"rendered":"https:\/\/www.almar.it\/?page_id=5751"},"modified":"2026-06-08T12:38:57","modified_gmt":"2026-06-08T10:38:57","slug":"cookie-erklaerung","status":"publish","type":"page","link":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/","title":{"rendered":"Cookie-Erkl\u00e4rung"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\"><strong>Cookie-Richtlinie<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">G\u00fcltigkeitsdatum: 23. April 2024<br>Zuletzt aktualisiert: 23. April 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was sind Cookies?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir einsetzen, also welche Informationen wir mithilfe von Cookies sammeln und wie diese Informationen genutzt werden sowie wie Sie die Cookie-Einstellungen verwalten k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cookies sind kleine Textdateien, die verwendet werden, um kleine Informationsmengen zu speichern. Sie werden auf Ihrem Ger\u00e4t gespeichert, wenn die Website in Ihrem Browser geladen wird. Diese Cookies helfen uns, die Website korrekt funktionieren zu lassen, sie sicherer zu machen, eine bessere Benutzererfahrung zu bieten, zu verstehen, wie die Website funktioniert, und zu analysieren, was gut funktioniert und wo Verbesserungen notwendig sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie verwenden wir Cookies?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie die meisten Online-Dienste verwendet unsere Website sowohl eigene als auch Cookies von Drittanbietern f\u00fcr verschiedene Zwecke. Eigene Cookies sind gr\u00f6\u00dftenteils notwendig, damit die Website ordnungsgem\u00e4\u00df funktioniert, und sie sammeln keine personenbezogenen, identifizierbaren Daten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die auf unserer Website verwendeten Cookies von Drittanbietern dienen haupts\u00e4chlich dazu, die Leistung der Website zu verstehen, wie Sie mit unserer Website interagieren, unsere Dienste sicher zu halten, Ihnen relevante Werbung bereitzustellen und insgesamt eine bessere und verbesserte Benutzererfahrung zu bieten sowie Ihre zuk\u00fcnftigen Interaktionen mit unserer Website zu beschleunigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Arten von Cookies, die wir verwenden<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookie-Einstellungen verwalten<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cookie-Einstellungen<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen Ihre Cookie-Einstellungen jederzeit \u00e4ndern, indem Sie auf die obenstehende Schaltfl\u00e4che klicken. Dadurch k\u00f6nnen Sie das Cookie-Banner erneut aufrufen und Ihre Einstellungen \u00e4ndern oder Ihre Zustimmung sofort widerrufen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus bieten verschiedene Browser unterschiedliche M\u00f6glichkeiten, die von Websites verwendeten Cookies zu blockieren und zu l\u00f6schen. Sie k\u00f6nnen die Einstellungen Ihres Browsers \u00e4ndern, um Cookies zu blockieren oder zu l\u00f6schen. Nachfolgend finden Sie Links zu den Support-Dokumenten zur Verwaltung und L\u00f6schung von Cookies in den wichtigsten Webbrowsern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chrome: https:\/\/support.google.com\/accounts\/answer\/32050<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Safari: https:\/\/support.apple.com\/en-in\/guide\/safari\/sfri11471\/mac<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Firefox: https:\/\/support.mozilla.org\/en-US\/kb\/clear-cookies-and-site-data-firefox?redirectslug=delete-cookies-remove-info-websites-stored&amp;redirectlocale=en-US<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet Explorer: https:\/\/support.microsoft.com\/en-us\/topic\/how-to-delete-cookie-files-in-internet-explorer-bca9446f-d873-78de-77ba-d42645fa52fc<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen anderen Webbrowser verwenden, besuchen Sie bitte die offiziellen Support-Dokumente Ihres Browsers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cookie-Richtlinie erstellt mit CookieYes \u2013 Cookie Policy Generator.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cookie-Richtlinie G\u00fcltigkeitsdatum: 23. April 2024Zuletzt aktualisiert: 23. April 2024 Was sind Cookies? Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir einsetzen, also welche Informationen wir mithilfe von Cookies sammeln und wie diese Informationen genutzt werden sowie wie Sie die Cookie-Einstellungen verwalten k\u00f6nnen. Cookies sind kleine Textdateien, die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-5751","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie-Erkl\u00e4rung - Almar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.almar.it\/de\/cookie-erklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie-Erkl\u00e4rung - Almar\" \/>\n<meta property=\"og:description\" content=\"Cookie-Richtlinie G\u00fcltigkeitsdatum: 23. April 2024Zuletzt aktualisiert: 23. April 2024 Was sind Cookies? Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir einsetzen, also welche Informationen wir mithilfe von Cookies sammeln und wie diese Informationen genutzt werden sowie wie Sie die Cookie-Einstellungen verwalten k\u00f6nnen. Cookies sind kleine Textdateien, die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.almar.it\/de\/cookie-erklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Almar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/almarmilano\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T10:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/01\/logo-almar-500x500-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/de\\\/cookie-erklaerung\\\/\",\"url\":\"https:\\\/\\\/www.almar.it\\\/de\\\/cookie-erklaerung\\\/\",\"name\":\"Cookie-Erkl\u00e4rung - Almar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/#website\"},\"datePublished\":\"2024-02-01T09:06:22+00:00\",\"dateModified\":\"2026-06-08T10:38:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/de\\\/cookie-erklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.almar.it\\\/de\\\/cookie-erklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/de\\\/cookie-erklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.almar.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie-Erkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/#website\",\"url\":\"https:\\\/\\\/www.almar.it\\\/\",\"name\":\"Almar Drink & Food\",\"description\":\"Preparati professionali Almar per bar, ristoranti e caff\u00e8\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/#organization\"},\"alternateName\":\"Almar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.almar.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/#organization\",\"name\":\"Almar Drink & Food srl\",\"url\":\"https:\\\/\\\/www.almar.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.almar.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.almar.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-almar-500x500-1.png\",\"contentUrl\":\"https:\\\/\\\/www.almar.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-almar-500x500-1.png\",\"width\":500,\"height\":500,\"caption\":\"Almar Drink & Food srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.almar.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/almarmilano\",\"https:\\\/\\\/www.instagram.com\\\/almar.gustoitaliano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/AlmarIT-Gusto-Italiano\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie-Erkl\u00e4rung - Almar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Cookie-Erkl\u00e4rung - Almar","og_description":"Cookie-Richtlinie G\u00fcltigkeitsdatum: 23. April 2024Zuletzt aktualisiert: 23. April 2024 Was sind Cookies? Diese Cookie-Richtlinie erkl\u00e4rt, was Cookies sind und wie wir sie verwenden, welche Arten von Cookies wir einsetzen, also welche Informationen wir mithilfe von Cookies sammeln und wie diese Informationen genutzt werden sowie wie Sie die Cookie-Einstellungen verwalten k\u00f6nnen. Cookies sind kleine Textdateien, die [&hellip;]","og_url":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/","og_site_name":"Almar","article_publisher":"https:\/\/www.facebook.com\/almarmilano","article_modified_time":"2026-06-08T10:38:57+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/01\/logo-almar-500x500-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/","url":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/","name":"Cookie-Erkl\u00e4rung - Almar","isPartOf":{"@id":"https:\/\/www.almar.it\/#website"},"datePublished":"2024-02-01T09:06:22+00:00","dateModified":"2026-06-08T10:38:57+00:00","breadcrumb":{"@id":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.almar.it\/de\/cookie-erklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.almar.it\/de\/cookie-erklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.almar.it\/de\/"},{"@type":"ListItem","position":2,"name":"Cookie-Erkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/www.almar.it\/#website","url":"https:\/\/www.almar.it\/","name":"Almar Drink & Food","description":"Preparati professionali Almar per bar, ristoranti e caff\u00e8","publisher":{"@id":"https:\/\/www.almar.it\/#organization"},"alternateName":"Almar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.almar.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.almar.it\/#organization","name":"Almar Drink & Food srl","url":"https:\/\/www.almar.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.almar.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/03\/logo-almar-500x500-1.png","contentUrl":"https:\/\/www.almar.it\/wp-content\/uploads\/2024\/03\/logo-almar-500x500-1.png","width":500,"height":500,"caption":"Almar Drink & Food srl"},"image":{"@id":"https:\/\/www.almar.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/almarmilano","https:\/\/www.instagram.com\/almar.gustoitaliano\/","https:\/\/www.youtube.com\/c\/AlmarIT-Gusto-Italiano"]}]}},"_links":{"self":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages\/5751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/comments?post=5751"}],"version-history":[{"count":1,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages\/5751\/revisions"}],"predecessor-version":[{"id":5754,"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/pages\/5751\/revisions\/5754"}],"wp:attachment":[{"href":"https:\/\/www.almar.it\/de\/wp-json\/wp\/v2\/media?parent=5751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}